{"id":20,"date":"2020-11-30T22:46:14","date_gmt":"2020-11-30T22:46:14","guid":{"rendered":"http:\/\/localhost:8888\/completehydraulic\/?page_id=20"},"modified":"2025-03-05T14:43:55","modified_gmt":"2025-03-05T14:43:55","slug":"home","status":"publish","type":"page","link":"https:\/\/www.completecomponent.com\/hydraulic\/","title":{"rendered":"Home"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-20","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.completecomponent.com\/hydraulic\/wp-json\/wp\/v2\/pages\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.completecomponent.com\/hydraulic\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.completecomponent.com\/hydraulic\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.completecomponent.com\/hydraulic\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.completecomponent.com\/hydraulic\/wp-json\/wp\/v2\/comments?post=20"}],"version-history":[{"count":124,"href":"https:\/\/www.completecomponent.com\/hydraulic\/wp-json\/wp\/v2\/pages\/20\/revisions"}],"predecessor-version":[{"id":24750,"href":"https:\/\/www.completecomponent.com\/hydraulic\/wp-json\/wp\/v2\/pages\/20\/revisions\/24750"}],"wp:attachment":[{"href":"https:\/\/www.completecomponent.com\/hydraulic\/wp-json\/wp\/v2\/media?parent=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}